{"id":26,"count":961,"description":"","link":"https:\/\/www.animelicenciado.es\/en_en\/category\/licencia\/","name":"Licencia","slug":"licencia","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.animelicenciado.es\/en_en\/wp-json\/wp\/v2\/categories\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.animelicenciado.es\/en_en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.animelicenciado.es\/en_en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.animelicenciado.es\/en_en\/wp-json\/wp\/v2\/posts?categories=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}